{"id":82261,"date":"2019-10-19T10:24:12","date_gmt":"2019-10-19T08:24:12","guid":{"rendered":"http:\/\/e-novatio.com\/?p=38"},"modified":"2019-11-26T11:43:45","modified_gmt":"2019-11-26T10:43:45","slug":"smart-industry-example","status":"publish","type":"post","link":"https:\/\/territorialchallenges.com\/it\/2019\/10\/19\/smart-industry-example\/82261\/","title":{"rendered":"Les machines-outils au XIX\u00e8me si\u00e8cle"},"content":{"rendered":"<p>Jean Chr\u00e9tien \u00e9tait un ing\u00e9nieur civil prolixe et rigoureux. Les 16 planches consacr\u00e9es aux machines-outils restent un mod\u00e8le de dessins industriels et d&rsquo;ouvrage th\u00e9orique et pratique. Edit\u00e9 en 1866, grande \u00e9poque de l&rsquo;industrialisation de la France, le document pr\u00e9sente les machines-outils employ\u00e9es dans les usines et ateliers de construction pour le travail des m\u00e9taux. N\u00e9&#8230; <\/p>\n<div class=\"pmpro_content_message\">Article uniquement consultable pour les abonn\u00e9s .<br \/><a href=\"https:\/\/territorialchallenges.com\/wp-login.php\">Connexion<\/a><br \/><a href=\"https:\/\/territorialchallenges.com\/it\/wp-login.php\/?action=register\">S&rsquo;inscrire<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Jean Chr\u00e9tien \u00e9tait un ing\u00e9nieur civil prolixe et rigoureux. Les 16 planches consacr\u00e9es aux machines-outils restent un mod\u00e8le de dessins industriels et d&rsquo;ouvrage th\u00e9orique et pratique. Edit\u00e9 en 1866, grande \u00e9poque de l&rsquo;industrialisation de la France, le document pr\u00e9sente les machines-outils employ\u00e9es dans les usines et ateliers de construction pour le travail des m\u00e9taux. N\u00e9... <\/p>\n<div class=\"pmpro_content_message\">Article uniquement consultable pour les abonn\u00e9s .<br \/><a href=\"https:\/\/territorialchallenges.com\/wp-login.php\">Connexion<\/a><br \/><a href=\"https:\/\/territorialchallenges.com\/it\/wp-login.php\/?action=register\">S'inscrire<\/a><\/div>","protected":false},"author":11,"featured_media":84899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":0,"footnotes":""},"categories":[121],"tags":[],"class_list":["post-82261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memoire","pmpro-level-required","pmpro-level-2","pmpro-level-3","pmpro-level-4","pmpro-level-5","pmpro-level-8","pmpro-level-6","pmpro-level-1","pmpro-no-access"],"blocksy_meta":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les machines-outils au XIX\u00e8me si\u00e8cle - Territorial Challenges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/territorialchallenges.com\/it\/2019\/10\/19\/smart-industry-example\/82261\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les machines-outils au XIX\u00e8me si\u00e8cle - Territorial Challenges\" \/>\n<meta property=\"og:description\" content=\"Jean Chr\u00e9tien \u00e9tait un ing\u00e9nieur civil prolixe et rigoureux. Les 16 planches consacr\u00e9es aux machines-outils restent un mod\u00e8le de dessins industriels et d&rsquo;ouvrage th\u00e9orique et pratique. Edit\u00e9 en 1866, grande \u00e9poque de l&rsquo;industrialisation de la France, le document pr\u00e9sente les machines-outils employ\u00e9es dans les usines et ateliers de construction pour le travail des m\u00e9taux. N\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/territorialchallenges.com\/it\/2019\/10\/19\/smart-industry-example\/82261\/\" \/>\n<meta property=\"og:site_name\" content=\"Territorial Challenges\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-19T08:24:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-26T10:43:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/territorialchallenges.com\/wp-content\/uploads\/2016\/06\/Lathe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"258\" \/>\n\t<meta property=\"og:image:height\" content=\"217\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ni.abdi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ni.abdi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ni.abdi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/\"},\"author\":{\"name\":\"ni.abdi\",\"@id\":\"https:\/\/territorialchallenges.com\/#\/schema\/person\/292686581c96a8d9ed175b9050deb3ba\"},\"headline\":\"Les machines-outils au XIX\u00e8me si\u00e8cle\",\"datePublished\":\"2019-10-19T08:24:12+00:00\",\"dateModified\":\"2019-11-26T10:43:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/\"},\"wordCount\":122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/territorialchallenges.com\/#organization\"},\"articleSection\":[\"M\u00e9moire\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/\",\"url\":\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/\",\"name\":\"Les machines-outils au XIX\u00e8me si\u00e8cle - Territorial Challenges\",\"isPartOf\":{\"@id\":\"https:\/\/territorialchallenges.com\/#website\"},\"datePublished\":\"2019-10-19T08:24:12+00:00\",\"dateModified\":\"2019-11-26T10:43:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/territorialchallenges.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les machines-outils au XIX\u00e8me si\u00e8cle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/territorialchallenges.com\/#website\",\"url\":\"https:\/\/territorialchallenges.com\/\",\"name\":\"Territorial Challenges\",\"description\":\"Veille Internationale - Strat\u00e9gie Intelligentes - Bonnes pratiques\",\"publisher\":{\"@id\":\"https:\/\/territorialchallenges.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/territorialchallenges.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/territorialchallenges.com\/#organization\",\"name\":\"Territorial Challenges\",\"url\":\"https:\/\/territorialchallenges.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/territorialchallenges.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/territorialchallenges.com\/wp-content\/uploads\/2023\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/territorialchallenges.com\/wp-content\/uploads\/2023\/10\/logo-1.png\",\"width\":1832,\"height\":576,\"caption\":\"Territorial Challenges\"},\"image\":{\"@id\":\"https:\/\/territorialchallenges.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/territorialchallenges.com\/#\/schema\/person\/292686581c96a8d9ed175b9050deb3ba\",\"name\":\"ni.abdi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/territorialchallenges.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd9bd80292d1c3945d917d3dd87ab6926e563d2b4469527c37028c275b05215b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd9bd80292d1c3945d917d3dd87ab6926e563d2b4469527c37028c275b05215b?s=96&d=identicon&r=g\",\"caption\":\"ni.abdi\"},\"sameAs\":[\"https:\/\/twitter.com\/Ni.abdi\"],\"url\":\"https:\/\/territorialchallenges.com\/it\/author\/ni-abdi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les machines-outils au XIX\u00e8me si\u00e8cle - Territorial Challenges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/territorialchallenges.com\/it\/2019\/10\/19\/smart-industry-example\/82261\/","og_locale":"it_IT","og_type":"article","og_title":"Les machines-outils au XIX\u00e8me si\u00e8cle - Territorial Challenges","og_description":"Jean Chr\u00e9tien \u00e9tait un ing\u00e9nieur civil prolixe et rigoureux. Les 16 planches consacr\u00e9es aux machines-outils restent un mod\u00e8le de dessins industriels et d&rsquo;ouvrage th\u00e9orique et pratique. Edit\u00e9 en 1866, grande \u00e9poque de l&rsquo;industrialisation de la France, le document pr\u00e9sente les machines-outils employ\u00e9es dans les usines et ateliers de construction pour le travail des m\u00e9taux. N\u00e9 [&hellip;]","og_url":"https:\/\/territorialchallenges.com\/it\/2019\/10\/19\/smart-industry-example\/82261\/","og_site_name":"Territorial Challenges","article_published_time":"2019-10-19T08:24:12+00:00","article_modified_time":"2019-11-26T10:43:45+00:00","og_image":[{"width":258,"height":217,"url":"https:\/\/territorialchallenges.com\/wp-content\/uploads\/2016\/06\/Lathe.png","type":"image\/png"}],"author":"ni.abdi","twitter_card":"summary_large_image","twitter_creator":"@Ni.abdi","twitter_misc":{"Scritto da":"ni.abdi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/#article","isPartOf":{"@id":"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/"},"author":{"name":"ni.abdi","@id":"https:\/\/territorialchallenges.com\/#\/schema\/person\/292686581c96a8d9ed175b9050deb3ba"},"headline":"Les machines-outils au XIX\u00e8me si\u00e8cle","datePublished":"2019-10-19T08:24:12+00:00","dateModified":"2019-11-26T10:43:45+00:00","mainEntityOfPage":{"@id":"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/"},"wordCount":122,"commentCount":0,"publisher":{"@id":"https:\/\/territorialchallenges.com\/#organization"},"articleSection":["M\u00e9moire"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/","url":"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/","name":"Les machines-outils au XIX\u00e8me si\u00e8cle - Territorial Challenges","isPartOf":{"@id":"https:\/\/territorialchallenges.com\/#website"},"datePublished":"2019-10-19T08:24:12+00:00","dateModified":"2019-11-26T10:43:45+00:00","breadcrumb":{"@id":"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/territorialchallenges.com\/2019\/10\/19\/smart-industry-example\/82261\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/territorialchallenges.com\/"},{"@type":"ListItem","position":2,"name":"Les machines-outils au XIX\u00e8me si\u00e8cle"}]},{"@type":"WebSite","@id":"https:\/\/territorialchallenges.com\/#website","url":"https:\/\/territorialchallenges.com\/","name":"Territorial Challenges","description":"Veille Internationale - Strat\u00e9gie Intelligentes - Bonnes pratiques","publisher":{"@id":"https:\/\/territorialchallenges.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/territorialchallenges.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/territorialchallenges.com\/#organization","name":"Territorial Challenges","url":"https:\/\/territorialchallenges.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/territorialchallenges.com\/#\/schema\/logo\/image\/","url":"https:\/\/territorialchallenges.com\/wp-content\/uploads\/2023\/10\/logo-1.png","contentUrl":"https:\/\/territorialchallenges.com\/wp-content\/uploads\/2023\/10\/logo-1.png","width":1832,"height":576,"caption":"Territorial Challenges"},"image":{"@id":"https:\/\/territorialchallenges.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/territorialchallenges.com\/#\/schema\/person\/292686581c96a8d9ed175b9050deb3ba","name":"ni.abdi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/territorialchallenges.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fd9bd80292d1c3945d917d3dd87ab6926e563d2b4469527c37028c275b05215b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd9bd80292d1c3945d917d3dd87ab6926e563d2b4469527c37028c275b05215b?s=96&d=identicon&r=g","caption":"ni.abdi"},"sameAs":["https:\/\/twitter.com\/Ni.abdi"],"url":"https:\/\/territorialchallenges.com\/it\/author\/ni-abdi\/"}]}},"_links":{"self":[{"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/posts\/82261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/comments?post=82261"}],"version-history":[{"count":1,"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/posts\/82261\/revisions"}],"predecessor-version":[{"id":84900,"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/posts\/82261\/revisions\/84900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/media\/84899"}],"wp:attachment":[{"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/media?parent=82261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/categories?post=82261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/territorialchallenges.com\/it\/wp-json\/wp\/v2\/tags?post=82261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}